{"id":10,"count":3,"description":"","link":"http:\/\/reemaalnasser.com\/blog\/category\/%d8%aa%d8%ac%d8%b1%d8%a8%d8%a9-%d8%ac%d8%af%d9%8a%d8%af%d8%a9\/","name":"\u062a\u062c\u0631\u0628\u0629 \u062c\u062f\u064a\u062f\u0629","slug":"%d8%aa%d8%ac%d8%b1%d8%a8%d8%a9-%d8%ac%d8%af%d9%8a%d8%af%d8%a9","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/reemaalnasser.com\/blog\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/reemaalnasser.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/reemaalnasser.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/reemaalnasser.com\/blog\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}